{"id":4347,"date":"2025-12-22T20:17:59","date_gmt":"2025-12-22T20:17:59","guid":{"rendered":"https:\/\/www.soysucre.info\/?p=4347"},"modified":"2025-12-22T21:50:58","modified_gmt":"2025-12-22T21:50:58","slug":"museo-del-chocolate","status":"publish","type":"post","link":"https:\/\/www.soysucre.info\/fr\/museo-del-chocolate\/","title":{"rendered":"Mus\u00e9e du chocolat"},"content":{"rendered":"<p>Imaginez-vous d\u00e9couvrir l&#8217;histoire du chocolat, de la graine au palais ?<\/p>\n<p>Nous proposons aux visiteurs de d\u00e9couvrir le Mus\u00e9e du Chocolat, un espace o\u00f9 ils pourront se familiariser avec l&#8217;univers du cacao. Depuis l&#8217;ann\u00e9e 1990, la marque s&#8217;attache \u00e0 transformer le cacao en douceur, et d\u00e9sire aujourd&#8217;hui partager cette exp\u00e9rience avec ses clients.<\/p>\n<p>Dans le cadre de cette \u00e9tude, une exploration approfondie des zones de production majeures du cacao en Bolivie et \u00e0 l&#8217;\u00e9chelle internationale sera conduite. Cette analyse portera sur les processus de culture et de transformation de ce produit, ainsi que sur les perceptions culturelles et les croyances associ\u00e9es \u00e0 cette plante dans diff\u00e9rentes civilisations, notamment parmi les peuples m\u00e9soam\u00e9ricains qui la consid\u00e9raient comme un \u00ab aliment des dieux \u00bb.<\/p>\n<p>Une observation attentive des r\u00e9cipients expos\u00e9s permettra de constater qu&#8217;ils ont \u00e9t\u00e9 fabriqu\u00e9s \u00e0 la main \u00e0 partir de mat\u00e9riaux naturels puis\u00e9s dans diff\u00e9rentes r\u00e9gions du pays. Dans le cadre de cette \u00e9tude, nous proc\u00e9derons \u00e9galement \u00e0 la narration de notre histoire.<\/p>\n<p>L&#8217;entreprise a \u00e9t\u00e9 fond\u00e9e il y a 35 ans, avec un capital initial de trois machines et sept collaborateurs. \u00c0 l&#8217;heure actuelle, l&#8217;entreprise figure parmi les principaux acteurs de l&#8217;industrie nationale.<\/p>\n<p>Cette exp\u00e9rience sensorielle, qui s&#8217;inscrit dans la continuit\u00e9 de la visite, offre une exploration exhaustive des ar\u00f4mes, des textures et des saveurs.<\/p>\n<p>&nbsp;<\/p>\n<p>LANGUE : Espagnol-anglais (sur demande pr\u00e9alable)<\/p>\n<p>DUR\u00c9E DE LA VISITE : 45 minutes.<\/p>\n<p>R\u00c9SERVATIONS : R\u00e9servez \u00e0 l&#8217;avance pour \u00eatre s\u00fbr d&#8217;avoir une place.<\/p>\n<p>&nbsp;<\/p>\n<p>Veuillez confirmer les informations suivantes :<\/p>\n<p>1. Heure de la visite.<\/p>\n<p>2. Nombre de personnes.<\/p>\n<p>3. Nom pour l&#8217;inscription (indispensable pour votre r\u00e9servation).<\/p>\n<p>4. Langue souhait\u00e9e.<\/p>\n<p>&nbsp;<\/p>\n<p>Veuillez noter que la visite concerne le mus\u00e9e du chocolat et non l&#8217;usine. En raison des r\u00e9glementations en mati\u00e8re de s\u00e9curit\u00e9 alimentaire, l&#8217;acc\u00e8s \u00e0 l&#8217;usine de production n&#8217;est pas autoris\u00e9.<\/p>\n<p>Nous sommes impatients de partager cette exp\u00e9rience avec vous.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Imaginez-vous d\u00e9couvrir l&#8217;histoire du chocolat, de la graine au palais ? Nous proposons aux visiteurs de d\u00e9couvrir le Mus\u00e9e du Chocolat, un espace o\u00f9 ils pourront se familiariser avec l&#8217;univers du cacao. Depuis l&#8217;ann\u00e9e 1990, la marque s&#8217;attache \u00e0 transformer le cacao en douceur, et d\u00e9sire aujourd&#8217;hui partager cette exp\u00e9rience avec ses clients. Dans le [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":4348,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[24,27,5,6],"tags":[808,1016,1026,1027,30,33,38,39,45,46,52,65,75,81,97,219],"class_list":["post-4347","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-museos","category-sitios","category-learn","category-cultura","tag-schokolade","tag-cacao","tag-wild","tag-sweet","tag-sucre","tag-natural","tag-chocolate","tag-para-ti","tag-tourist","tag-information","tag-bolivia","tag-museum","tag-top","tag-food","tag-best","tag-boliviano"],"translation":{"provider":"WPGlobus","version":"3.0.2","language":"fr","enabled_languages":["en","es","fr"],"languages":{"en":{"title":true,"content":true,"excerpt":false},"es":{"title":true,"content":true,"excerpt":false},"fr":{"title":true,"content":true,"excerpt":false}}},"acf":[],"_links":{"self":[{"href":"https:\/\/www.soysucre.info\/fr\/wp-json\/wp\/v2\/posts\/4347","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.soysucre.info\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.soysucre.info\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.soysucre.info\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.soysucre.info\/fr\/wp-json\/wp\/v2\/comments?post=4347"}],"version-history":[{"count":5,"href":"https:\/\/www.soysucre.info\/fr\/wp-json\/wp\/v2\/posts\/4347\/revisions"}],"predecessor-version":[{"id":4358,"href":"https:\/\/www.soysucre.info\/fr\/wp-json\/wp\/v2\/posts\/4347\/revisions\/4358"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.soysucre.info\/fr\/wp-json\/wp\/v2\/media\/4348"}],"wp:attachment":[{"href":"https:\/\/www.soysucre.info\/fr\/wp-json\/wp\/v2\/media?parent=4347"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.soysucre.info\/fr\/wp-json\/wp\/v2\/categories?post=4347"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.soysucre.info\/fr\/wp-json\/wp\/v2\/tags?post=4347"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}