{"id":1345,"date":"2017-06-02T23:43:39","date_gmt":"2017-06-02T23:43:39","guid":{"rendered":"http:\/\/www.soysucre.info\/?p=1345"},"modified":"2025-07-01T21:07:06","modified_gmt":"2025-07-01T21:07:06","slug":"hotel-restaurante-la-posada","status":"publish","type":"post","link":"https:\/\/www.soysucre.info\/fr\/hotel-restaurante-la-posada\/","title":{"rendered":"Hotel Boutique Restaurante La Posada"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p>Au fil des ans, La Posada s&#8217;est forg\u00e9 une r\u00e9putation gr\u00e2ce \u00e0 son style unique, son service personnalis\u00e9 et son atmosph\u00e8re accueillante. Aujourd&#8217;hui, nous sommes fiers de r\u00e9affirmer notre engagement envers l&#8217;excellence et de nous \u00e9tablir officiellement comme :<\/p>\n<p>LA POSADA BOUTIQUE HOTEL<\/p>\n<p>Avec une classification <span style=\"font-size: 20px;\">4 \u00e9toiles<\/span><\/p>\n<p>Nous avons le plaisir de vous accueillir dans notre \u00e9tablissement, une grande maison coloniale restaur\u00e9e avec go\u00fbt, qui allie charme et fonctionnalit\u00e9. Nos espaces sont pens\u00e9s pour vous offrir un moment de d\u00e9tente et de s\u00e9r\u00e9nit\u00e9. De plus, notre restaurant, reconnu et recommand\u00e9 par des guides touristiques de renom tels que Lonely Planet, est un atout qui nous positionne parmi les v\u00e9ritables h\u00f4tels-boutiques, selon les normes internationales.<\/p>\n<p>Situ\u00e9 au c\u0153ur du centre historique de Sucre, La Posada vous invite \u00e0 vivre une exp\u00e9rience culinaire unique alliant tradition bolivienne et saveurs internationales. Install\u00e9 dans un magnifique manoir colonial restaur\u00e9, le restaurant dispose d&#8217;une charmante cour et d&#8217;un salon int\u00e9rieur spacieux o\u00f9 vous pourrez vous d\u00e9tendre. Le menu vari\u00e9 r\u00e9pond \u00e0 tous les go\u00fbts, proposant des plats traditionnels tels que le Mondongo, mais aussi des options internationales comme le Cordon Bleu, ainsi que du poisson, de la viande, des fruits de mer, des p\u00e2tes, des salades, des caf\u00e9s et des desserts. C&#8217;est un endroit id\u00e9al pour les d\u00e9jeuners en semaine et les d\u00eeners sp\u00e9ciaux.<\/p>\n<p>C&#8217;est un incontournable de la route gastronomique de Sucre.<\/p>\n<h2><strong>Sp\u00e9cialit\u00e9s<\/strong><\/h2>\n<p>Plats typiques de Bolivie<\/p>\n<p>Plats internationaux<\/p>\n<p>Options v\u00e9g\u00e9tariennes<\/p>\n<p>Vins et bi\u00e8res<\/p>\n<p>Caf\u00e9t\u00e9ria<\/p>\n<p>&nbsp;<\/p>\n<p>Nous serons ravis de vous accueillir avec la m\u00eame chaleur que d&#8217;habitude.<\/p>\n<p>Bienvenue \u00e0 l&#8217;H\u00d4TEL BOUTIQUE LA POSADA.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Au fil des ans, La Posada s&#8217;est forg\u00e9 une r\u00e9putation gr\u00e2ce \u00e0 son style unique, son service personnalis\u00e9 et son atmosph\u00e8re accueillante. Aujourd&#8217;hui, nous sommes fiers de r\u00e9affirmer notre engagement envers l&#8217;excellence et de nous \u00e9tablir officiellement comme : LA POSADA BOUTIQUE HOTEL Avec une classification 4 \u00e9toiles Nous avons le plaisir de vous [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":1346,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[12,17,8,9],"tags":[79,490,83,493,97,519,120,640,152,646,189,704,193,706,200,707,359,708,398,710,399,712,401,713,460,714,478,13,486,78,489],"class_list":["post-1345","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-lujo","category-restaurant-cafe","category-dormir","category-comer","tag-cafe","tag-experiencia","tag-restaurant","tag-specialise","tag-best","tag-sopa","tag-centre","tag-tranquillo","tag-the","tag-next","tag-cheap","tag-audiencia","tag-hostal","tag-vino","tag-tea","tag-tee","tag-gourmet","tag-sleep-quite","tag-dormir","tag-nivel","tag-centro","tag-close","tag-price","tag-to","tag-range","tag-nightlife","tag-untappd","tag-hotel","tag-higienico","tag-plaza","tag-trust"],"translation":{"provider":"WPGlobus","version":"3.0.2","language":"fr","enabled_languages":["en","es","fr"],"languages":{"en":{"title":true,"content":true,"excerpt":false},"es":{"title":true,"content":true,"excerpt":false},"fr":{"title":true,"content":true,"excerpt":false}}},"acf":[],"_links":{"self":[{"href":"https:\/\/www.soysucre.info\/fr\/wp-json\/wp\/v2\/posts\/1345","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.soysucre.info\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.soysucre.info\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.soysucre.info\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.soysucre.info\/fr\/wp-json\/wp\/v2\/comments?post=1345"}],"version-history":[{"count":15,"href":"https:\/\/www.soysucre.info\/fr\/wp-json\/wp\/v2\/posts\/1345\/revisions"}],"predecessor-version":[{"id":3947,"href":"https:\/\/www.soysucre.info\/fr\/wp-json\/wp\/v2\/posts\/1345\/revisions\/3947"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.soysucre.info\/fr\/wp-json\/wp\/v2\/media\/1346"}],"wp:attachment":[{"href":"https:\/\/www.soysucre.info\/fr\/wp-json\/wp\/v2\/media?parent=1345"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.soysucre.info\/fr\/wp-json\/wp\/v2\/categories?post=1345"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.soysucre.info\/fr\/wp-json\/wp\/v2\/tags?post=1345"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}